{"id":65666,"date":"2023-12-18T14:02:34","date_gmt":"2023-12-18T18:02:34","guid":{"rendered":"https:\/\/www.smartcommunications.com\/?page_id=65666"},"modified":"2026-06-30T12:28:37","modified_gmt":"2026-06-30T16:28:37","slug":"kontakt","status":"publish","type":"page","link":"https:\/\/www.smartcommunications.com\/de\/kontakt\/","title":{"rendered":"Contact Us"},"content":{"rendered":"[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;76&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in-from-bottom&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; delay=&#8220;500&#8243;][vc_custom_heading text=&#8220;Unsere B\u00fcrostandorte&#8220; font_container=&#8220;tag:h3|text_align:center|color:%23183958&#8243; use_theme_fonts=&#8220;yes&#8220; el_class=&#8220;heading-line-center&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;42&#8243; bottom_padding=&#8220;11&#8243; top_margin=&#8220;-1px&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in-from-bottom&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; delay=&#8220;500&#8243;][smartc_pages pages_style=&#8220;contact-us-style&#8220;][page_items title=&#8220;Gro\u00dfbritannien&#8220; anchor=&#8220;page-1&#8243;][page_items title=&#8220;Nordamerika&#8220; anchor=&#8220;page-2&#8243;][page_items title=&#8220;Asien-Pazifik&#8220; anchor=&#8220;page-3&#8243;][page_items active_item=&#8220;true&#8220; title=&#8220;Europe&#8220; anchor=&#8220;page-4&#8243;][\/smartc_pages][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;65&#8243; bottom_padding=&#8220;90&#8243; left_padding_desktop=&#8220;13&#8243; right_padding_desktop=&#8220;13&#8243; top_padding_tablet=&#8220;60&#8243; top_padding_phone=&#8220;50&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;pages-row page-1&#8243; advanced_gradient_angle=&#8220;0&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; right_margin=&#8220;20&#8243; right_margin_tablet=&#8220;0&#8243; column_element_spacing=&#8220;default&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; el_class=&#8220;padding-0 contact-us-location-card&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in-from-bottom&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;1px&#8220; column_border_color=&#8220;#eaeaea&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; delay=&#8220;500&#8243;][image_with_animation image_url=&#8220;53824&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; margin_top=&#8220;10&#8243; margin_bottom=&#8220;50&#8243; margin_left=&#8220;10&#8243; margin_right=&#8220;10&#8243; el_class=&#8220;full-image-width&#8220; margin_bottom_tablet=&#8220;40&#8243; margin_bottom_phone=&#8220;35&#8243;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bottom_padding=&#8220;40&#8243; left_padding_desktop=&#8220;35&#8243; right_padding_desktop=&#8220;30&#8243; bottom_padding_phone=&#8220;30&#8243; left_padding_phone=&#8220;20&#8243; right_padding_phone=&#8220;20&#8243; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;padding-7-percent&#8220; column_padding_tablet=&#8220;padding-5-percent&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;right&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; el_class=&#8220;padding-0&#8243; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][vc_custom_heading text=&#8220;Elstree&#8220; font_container=&#8220;tag:p|font_size:36px|text_align:left|color:%230a3184|line_height:42px&#8220; use_theme_fonts=&#8220;yes&#8220; el_class=&#8220;bold margin-0 padding-0&#8243;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;26px&#8220; custom_height_tablet=&#8220;25px&#8220; custom_height_phone=&#8220;20px&#8220;][vc_column_text el_class=&#8220;small-text&#8220; css=&#8220;.vc_custom_1704222885120{padding-right: 10px !important;}&#8220;]<span style=\"color: #326eef; font-weight: 500;\">Registered Office<\/span><br \/>\n<span style=\"color: #3e3e3e;\">Smart Communications<\/span><br \/>\n<span style=\"color: #3e3e3e;\">Suite 23<\/span><br \/>\n<span style=\"color: #3e3e3e;\">LCLB<\/span><br \/>\n<span style=\"color: #3e3e3e;\">95 Mortimer Street<\/span><br \/>\n<span style=\"color: #3e3e3e;\">London<\/span><br \/>\n<span style=\"color: #3e3e3e;\">W1W 7GB<\/span>[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; el_class=&#8220;padding-0&#8243; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">Telefonnummer<\/span><br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"tel:+4403452412339\">+44 (0)345 241 2339<\/a><\/span>[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20px&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">Support-Telefonnummer <\/span><br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"tel:+4403452412338\">+44 (0)345 241 2338<\/a><\/span>[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20px&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">E-Mail-Adresse<br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"mailto:requests@smartcommunications.com\">requests@smartcommunications.com<\/a><\/span><\/span>[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20px&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">Support-Anfrage<br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"mailto:support@smartcommunications.com\">support@smartcommunications.com<\/a><\/span><\/span>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; left_margin=&#8220;20&#8243; left_margin_tablet=&#8220;0&#8243; column_element_spacing=&#8220;default&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; el_class=&#8220;padding-0 contact-us-location-card&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in-from-bottom&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;1px&#8220; column_border_color=&#8220;#eaeaea&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; delay=&#8220;500&#8243;][image_with_animation image_url=&#8220;53826&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; margin_top=&#8220;10&#8243; margin_bottom=&#8220;50&#8243; margin_left=&#8220;10&#8243; margin_right=&#8220;10&#8243; el_class=&#8220;full-image-width&#8220; margin_bottom_tablet=&#8220;40&#8243; margin_bottom_phone=&#8220;35&#8243;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bottom_padding=&#8220;40&#8243; left_padding_desktop=&#8220;35&#8243; right_padding_desktop=&#8220;30&#8243; bottom_padding_phone=&#8220;30&#8243; left_padding_phone=&#8220;20&#8243; right_padding_phone=&#8220;20&#8243; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;padding-7-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;right&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; el_class=&#8220;padding-0&#8243; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][vc_custom_heading text=&#8220;London&#8220; font_container=&#8220;tag:p|font_size:36px|text_align:left|color:%230a3184|line_height:42px&#8220; use_theme_fonts=&#8220;yes&#8220; el_class=&#8220;bold margin-0 padding-0&#8243;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;26px&#8220; custom_height_tablet=&#8220;25px&#8220; custom_height_phone=&#8220;20px&#8220;][vc_column_text el_class=&#8220;small-text&#8220;]<span style=\"color: #326eef; font-weight: 500;\">Trading Office<\/span><br \/>\n<span style=\"color: #3e3e3e;\">Smart Communications<\/span><br \/>\n<span style=\"color: #3e3e3e;\">14 Floral Street<\/span><br \/>\n<span style=\"color: #3e3e3e;\">Covent Garden<\/span><br \/>\n<span style=\"color: #3e3e3e;\">London,<\/span><br \/>\n<span style=\"color: #3e3e3e;\">WC2E 9DH<\/span>[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; el_class=&#8220;padding-0&#8243; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">Telefonnummer <\/span><br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"tel:+4403452412339\">+44 (0)345 241 2339<\/a><\/span>[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20px&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">Support-Telefonnummer <\/span><br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"tel:+4403452412338\">+44 (0)345 241 2338<\/a><\/span>[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20px&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">E-Mail-Adresse<br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"mailto:requests@smartcommunications.com\">requests@smartcommunications.com<\/a><\/span><\/span>[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20px&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">Support-Anfrage<br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"mailto:support@smartcommunications.com\">support@smartcommunications.com<\/a><\/span><\/span>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;65&#8243; bottom_padding=&#8220;90&#8243; left_padding_desktop=&#8220;13&#8243; right_padding_desktop=&#8220;13&#8243; top_padding_tablet=&#8220;60&#8243; top_padding_phone=&#8220;50&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;pages-row page-2&#8243; advanced_gradient_angle=&#8220;0&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; right_margin=&#8220;20&#8243; right_margin_tablet=&#8220;0&#8243; column_element_spacing=&#8220;default&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; el_class=&#8220;padding-0 contact-us-location-card&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;1px&#8220; column_border_color=&#8220;#eaeaea&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][image_with_animation image_url=&#8220;53866&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; margin_top=&#8220;10&#8243; margin_bottom=&#8220;50&#8243; margin_left=&#8220;10&#8243; margin_right=&#8220;10&#8243; el_class=&#8220;full-image-width&#8220; margin_bottom_tablet=&#8220;40&#8243; margin_bottom_phone=&#8220;35&#8243;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bottom_padding=&#8220;40&#8243; left_padding_desktop=&#8220;35&#8243; right_padding_desktop=&#8220;30&#8243; bottom_padding_phone=&#8220;30&#8243; left_padding_phone=&#8220;20&#8243; right_padding_phone=&#8220;20&#8243; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;padding-7-percent&#8220; column_padding_tablet=&#8220;padding-5-percent&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;right&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; el_class=&#8220;padding-0&#8243; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][vc_custom_heading text=&#8220;USA&#8220; font_container=&#8220;tag:p|font_size:36px|text_align:left|color:%230a3184|line_height:42px&#8220; use_theme_fonts=&#8220;yes&#8220; el_class=&#8220;bold margin-0 padding-0&#8243;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;26px&#8220; custom_height_tablet=&#8220;25px&#8220; custom_height_phone=&#8220;20px&#8220;][vc_column_text el_class=&#8220;small-text&#8220;]<span style=\"color: #3e3e3e;\">Smart Communications<\/span><br \/>\n<span style=\"color: #3e3e3e;\">18208 Preston Rd,<\/span><br \/>\n<span style=\"color: #3e3e3e;\">Suite D9 #350<\/span><br \/>\n<span style=\"color: #3e3e3e;\">Dallas, Texas<\/span><br \/>\n<span style=\"color: #3e3e3e;\">75252<\/span>[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; el_class=&#8220;padding-0&#8243; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">Telefonnummer<\/span><br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"tel:+18009866810\">+1 800 986 6810<\/a><\/span>[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20px&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">Support-Telefonnummer<\/span><br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"tel:+18009866315\">+1 800 986 6315<\/a><\/span>[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20px&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">E-Mail-Adresse<br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"mailto:requests@smartcommunications.com\">requests@smartcommunications.com<\/a><\/span><\/span>[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20px&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">Support-Anfrage<br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"mailto:support@smartcommunications.com\">support@smartcommunications.com<\/a><\/span><\/span>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; left_margin=&#8220;20&#8243; left_margin_tablet=&#8220;0&#8243; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; el_class=&#8220;padding-0 contact-us-location-card&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_color=&#8220;#eaeaea&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;65&#8243; bottom_padding=&#8220;90&#8243; left_padding_desktop=&#8220;13&#8243; right_padding_desktop=&#8220;13&#8243; top_padding_tablet=&#8220;60&#8243; bottom_padding_tablet=&#8220;25&#8243; top_padding_phone=&#8220;50&#8243; bottom_padding_phone=&#8220;25&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;pages-row page-3&#8243; advanced_gradient_angle=&#8220;0&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; right_margin=&#8220;20&#8243; right_margin_tablet=&#8220;0&#8243; column_element_spacing=&#8220;default&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; el_class=&#8220;padding-0 contact-us-location-card&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;1px&#8220; column_border_color=&#8220;#eaeaea&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][image_with_animation image_url=&#8220;53872&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; margin_top=&#8220;10&#8243; margin_bottom=&#8220;50&#8243; margin_left=&#8220;10&#8243; margin_right=&#8220;10&#8243; el_class=&#8220;full-image-width&#8220; margin_bottom_tablet=&#8220;40&#8243; margin_bottom_phone=&#8220;35&#8243;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bottom_padding=&#8220;40&#8243; left_padding_desktop=&#8220;35&#8243; right_padding_desktop=&#8220;30&#8243; bottom_padding_phone=&#8220;30&#8243; left_padding_phone=&#8220;20&#8243; right_padding_phone=&#8220;20&#8243; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;padding-7-percent&#8220; column_padding_tablet=&#8220;padding-5-percent&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;right&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; el_class=&#8220;padding-0&#8243; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][vc_custom_heading text=&#8220;Australien&#8220; font_container=&#8220;tag:p|font_size:36px|text_align:left|color:%230a3184|line_height:42px&#8220; use_theme_fonts=&#8220;yes&#8220; el_class=&#8220;bold margin-0 padding-0&#8243;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;26px&#8220; custom_height_tablet=&#8220;25px&#8220; custom_height_phone=&#8220;20px&#8220;][vc_column_text el_class=&#8220;small-text&#8220;]Smart Communications<br \/>\nLevel 1<br \/>\n355 Crown Street<br \/>\nSurry Hills, NSW, 2010<br \/>\nAustralia[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; el_class=&#8220;padding-0&#8243; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;70px&#8220; custom_height_tablet=&#8220;0&#8243; custom_height_phone=&#8220;0&#8243;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">Telefonnummer<\/span><br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"tel:+61280004020\">+61 2 8000 4020<\/a><\/span>[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20px&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">E-Mail-Adresse<br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"mailto:requests@smartcommunications.com\">requests@smartcommunications.com<\/a><\/span><\/span>[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20px&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">Support-Anfrage<br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"mailto:support@smartcommunications.com\">support@smartcommunications.com<\/a><\/span><\/span>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; left_margin=&#8220;20&#8243; left_margin_tablet=&#8220;0&#8243; column_element_spacing=&#8220;default&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; el_class=&#8220;padding-0 contact-us-location-card&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;1px&#8220; column_border_color=&#8220;#eaeaea&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][image_with_animation image_url=&#8220;53864&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; margin_top=&#8220;10&#8243; margin_bottom=&#8220;50&#8243; margin_left=&#8220;10&#8243; margin_right=&#8220;10&#8243; el_class=&#8220;full-image-width&#8220; margin_bottom_tablet=&#8220;40&#8243; margin_bottom_phone=&#8220;35&#8243;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bottom_padding=&#8220;40&#8243; left_padding_desktop=&#8220;35&#8243; right_padding_desktop=&#8220;30&#8243; bottom_padding_phone=&#8220;30&#8243; left_padding_phone=&#8220;20&#8243; right_padding_phone=&#8220;20&#8243; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;padding-7-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;right&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; el_class=&#8220;padding-0&#8243; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][vc_custom_heading text=&#8220;Australien&#8220; font_container=&#8220;tag:p|font_size:36px|text_align:left|color:%230a3184|line_height:42px&#8220; use_theme_fonts=&#8220;yes&#8220; el_class=&#8220;bold margin-0 padding-0&#8243;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;26px&#8220; custom_height_tablet=&#8220;25px&#8220; custom_height_phone=&#8220;20px&#8220;][vc_column_text el_class=&#8220;small-text&#8220;]<span style=\"color: #3e3e3e;\">Smart Communications<\/span><br \/>\n<span style=\"color: #3e3e3e;\">Hub Civic Quarter,<\/span><br \/>\n<span style=\"color: #3e3e3e;\">Office 2019 S<\/span><br \/>\n<span style=\"color: #3e3e3e;\">68 Northbourne Avenue,<\/span><br \/>\n<span style=\"color: #3e3e3e;\">Canberra 2600, ACT<\/span>[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; el_class=&#8220;padding-0&#8243; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;70px&#8220; custom_height_tablet=&#8220;0&#8243; custom_height_phone=&#8220;0&#8243;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">Telefonnummer<\/span><br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"tel:+61280004020\">+61 2 8000 4020<\/a><\/span>[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20px&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">E-Mail-Adresse<br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"mailto:requests@smartcommunications.com\">requests@smartcommunications.com<\/a><\/span><\/span>[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20px&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">Support-Anfrage<br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"mailto:support@smartcommunications.com\">support@smartcommunications.com<\/a><\/span><\/span>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; bottom_padding=&#8220;90&#8243; left_padding_desktop=&#8220;13&#8243; right_padding_desktop=&#8220;13&#8243; bottom_padding_tablet=&#8220;0&#8243; bottom_padding_phone=&#8220;0&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;pages-row page-3&#8243; advanced_gradient_angle=&#8220;0&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; right_margin=&#8220;20&#8243; right_margin_tablet=&#8220;0&#8243; column_element_spacing=&#8220;default&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; el_class=&#8220;padding-0 contact-us-location-card&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;1px&#8220; column_border_color=&#8220;#eaeaea&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][image_with_animation image_url=&#8220;53870&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; margin_top=&#8220;10&#8243; margin_bottom=&#8220;50&#8243; margin_left=&#8220;10&#8243; margin_right=&#8220;10&#8243; el_class=&#8220;full-image-width&#8220; margin_bottom_tablet=&#8220;40&#8243; margin_bottom_phone=&#8220;35&#8243;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bottom_padding=&#8220;40&#8243; left_padding_desktop=&#8220;35&#8243; right_padding_desktop=&#8220;30&#8243; bottom_padding_phone=&#8220;30&#8243; left_padding_phone=&#8220;20&#8243; right_padding_phone=&#8220;20&#8243; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;padding-7-percent&#8220; column_padding_tablet=&#8220;padding-5-percent&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;right&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; el_class=&#8220;padding-0&#8243; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][vc_custom_heading text=&#8220;Singapur&#8220; font_container=&#8220;tag:p|font_size:36px|text_align:left|color:%230a3184|line_height:42px&#8220; use_theme_fonts=&#8220;yes&#8220; el_class=&#8220;bold margin-0 padding-0&#8243;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;26px&#8220; custom_height_tablet=&#8220;25px&#8220; custom_height_phone=&#8220;20px&#8220;][vc_column_text el_class=&#8220;small-text&#8220;]<span style=\"color: #3e3e3e;\">Smart Communications<\/span><br \/>\nWeWork<br \/>\n9 Battery Rd #28-01<br \/>\nSingapore 049910[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; el_class=&#8220;padding-0&#8243; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;70px&#8220; custom_height_tablet=&#8220;0&#8243; custom_height_phone=&#8220;0&#8243;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">Telefonnummer<\/span><br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"tel:+6560111748\">+65 6011 1748<\/a><\/span>[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20px&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">E-Mail-Adresse<br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"mailto:requests@smartcommunications.com\">requests@smartcommunications.com<\/a><\/span><\/span>[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20px&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">Support-Anfrage<br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"mailto:support@smartcommunications.com\">support@smartcommunications.com<\/a><\/span><\/span>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; left_margin=&#8220;20&#8243; left_margin_tablet=&#8220;0&#8243; column_element_spacing=&#8220;default&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; el_class=&#8220;padding-0 contact-us-location-card&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;1px&#8220; column_border_color=&#8220;#eaeaea&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][image_with_animation image_url=&#8220;53868&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; margin_top=&#8220;10&#8243; margin_bottom=&#8220;50&#8243; margin_left=&#8220;10&#8243; margin_right=&#8220;10&#8243; el_class=&#8220;full-image-width&#8220; margin_bottom_tablet=&#8220;40&#8243; margin_bottom_phone=&#8220;35&#8243;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; left_padding_desktop=&#8220;35&#8243; right_padding_desktop=&#8220;30&#8243; left_padding_phone=&#8220;20&#8243; right_padding_phone=&#8220;20&#8243; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; el_class=&#8220;padding-0&#8243; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][vc_custom_heading text=&#8220;Neuseeland&#8220; font_container=&#8220;tag:p|font_size:36px|text_align:left|color:%230a3184|line_height:42px&#8220; use_theme_fonts=&#8220;yes&#8220; el_class=&#8220;bold margin-0 padding-0&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bottom_padding=&#8220;40&#8243; left_padding_desktop=&#8220;35&#8243; right_padding_desktop=&#8220;30&#8243; bottom_padding_phone=&#8220;30&#8243; left_padding_phone=&#8220;20&#8243; right_padding_phone=&#8220;20&#8243; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; el_class=&#8220;padding-0&#8243; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;6px&#8220; custom_height_tablet=&#8220;0&#8243; custom_height_phone=&#8220;0&#8243;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">Telefonnummer<\/span><br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"tel:+6432881960\">+64 3288 1960<\/a><\/span>[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20px&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">E-Mail-Adresse<br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"mailto:requests@smartcommunications.com\">requests@smartcommunications.com<\/a><\/span><\/span>[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;51px&#8220; custom_height_tablet=&#8220;0px&#8220;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;65&#8243; bottom_padding=&#8220;90&#8243; left_padding_desktop=&#8220;13&#8243; right_padding_desktop=&#8220;13&#8243; top_padding_tablet=&#8220;60&#8243; bottom_padding_tablet=&#8220;25&#8243; top_padding_phone=&#8220;50&#8243; bottom_padding_phone=&#8220;25&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;pages-row page-4 visible&#8220; advanced_gradient_angle=&#8220;0&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; right_margin=&#8220;20&#8243; right_margin_tablet=&#8220;0&#8243; column_element_spacing=&#8220;default&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; el_class=&#8220;padding-0 contact-us-location-card&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;1px&#8220; column_border_color=&#8220;#eaeaea&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][image_with_animation image_url=&#8220;53892&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; margin_top=&#8220;10&#8243; margin_bottom=&#8220;50&#8243; margin_left=&#8220;10&#8243; margin_right=&#8220;10&#8243; el_class=&#8220;full-image-width&#8220; margin_bottom_tablet=&#8220;40&#8243; margin_bottom_phone=&#8220;35&#8243;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bottom_padding=&#8220;40&#8243; left_padding_desktop=&#8220;35&#8243; right_padding_desktop=&#8220;30&#8243; bottom_padding_phone=&#8220;30&#8243; left_padding_phone=&#8220;20&#8243; right_padding_phone=&#8220;20&#8243; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;padding-7-percent&#8220; column_padding_tablet=&#8220;padding-5-percent&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;right&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; el_class=&#8220;padding-0&#8243; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][vc_custom_heading text=&#8220;Deutschland&#8220; font_container=&#8220;tag:p|font_size:36px|text_align:left|color:%230a3184|line_height:42px&#8220; use_theme_fonts=&#8220;yes&#8220; el_class=&#8220;bold margin-0 padding-0&#8243;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;26px&#8220; custom_height_tablet=&#8220;25px&#8220; custom_height_phone=&#8220;20px&#8220;][vc_column_text el_class=&#8220;small-text&#8220;]<span style=\"color: #3e3e3e;\">SmartComms GmbH<\/span><br \/>\n<span style=\"color: #3e3e3e;\">St. Johanner Stra\u00dfe 41 \u2013 43<\/span><br \/>\n<span style=\"color: #3e3e3e;\">66111 Saarbruecken<\/span>[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; el_class=&#8220;padding-0&#8243; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;70px&#8220; custom_height_tablet=&#8220;0&#8243; custom_height_phone=&#8220;0&#8243;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">Telefonnummer<\/span><br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"tel:+49681397850\">+49 681 397 850<\/a><\/span>[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20px&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">E-Mail-Adresse<br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"mailto:requests@smartcommunications.com\">requests@smartcommunications.com<\/a><\/span><\/span>[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20px&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">Support-Anfrage<br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"mailto:support@smartcommunications.com\">support@smartcommunications.com<\/a><\/span><\/span>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; left_margin=&#8220;20&#8243; left_margin_tablet=&#8220;0&#8243; column_element_spacing=&#8220;default&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; el_class=&#8220;padding-0 contact-us-location-card&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;1px&#8220; column_border_color=&#8220;#eaeaea&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][image_with_animation image_url=&#8220;53894&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; margin_top=&#8220;10&#8243; margin_bottom=&#8220;50&#8243; margin_left=&#8220;10&#8243; margin_right=&#8220;10&#8243; el_class=&#8220;full-image-width&#8220; margin_bottom_tablet=&#8220;40&#8243; margin_bottom_phone=&#8220;35&#8243;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bottom_padding=&#8220;40&#8243; left_padding_desktop=&#8220;35&#8243; right_padding_desktop=&#8220;30&#8243; bottom_padding_phone=&#8220;30&#8243; left_padding_phone=&#8220;20&#8243; right_padding_phone=&#8220;20&#8243; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;padding-7-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;right&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; el_class=&#8220;padding-0&#8243; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][vc_custom_heading text=&#8220;Schweiz&#8220; font_container=&#8220;tag:p|font_size:36px|text_align:left|color:%230a3184|line_height:42px&#8220; use_theme_fonts=&#8220;yes&#8220; el_class=&#8220;bold margin-0 padding-0&#8243;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;26px&#8220; custom_height_tablet=&#8220;25px&#8220; custom_height_phone=&#8220;20px&#8220;][vc_column_text el_class=&#8220;small-text&#8220;]<span style=\"color: #3e3e3e;\">Smart Communications<\/span><br \/>\n<span style=\"color: #3e3e3e;\">Blegistrasse 1<\/span><br \/>\n<span style=\"color: #3e3e3e;\">6343 Rotkreuz<\/span>[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; el_class=&#8220;padding-0&#8243; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;70px&#8220; custom_height_tablet=&#8220;0&#8243; custom_height_phone=&#8220;0&#8243;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">Telefonnummer<\/span><br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"tel:+41417909192\">+41 41 790 91 92<\/a><\/span>[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20px&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">E-Mail-Adresse<br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"mailto:requests@smartcommunications.com\">requests@smartcommunications.com<\/a><\/span><\/span>[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20px&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">Support-Anfrage<br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"mailto:support@smartcommunications.com\">support@smartcommunications.com<\/a><\/span><\/span>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; bottom_padding=&#8220;90&#8243; left_padding_desktop=&#8220;13&#8243; right_padding_desktop=&#8220;13&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;pages-row page-4 visible&#8220; advanced_gradient_angle=&#8220;0&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; right_margin=&#8220;20&#8243; right_margin_tablet=&#8220;0&#8243; column_element_spacing=&#8220;default&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; el_class=&#8220;padding-0 contact-us-location-card&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;1px&#8220; column_border_color=&#8220;#eaeaea&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][image_with_animation image_url=&#8220;53890&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; margin_top=&#8220;10&#8243; margin_bottom=&#8220;50&#8243; margin_left=&#8220;10&#8243; margin_right=&#8220;10&#8243; el_class=&#8220;full-image-width&#8220; margin_bottom_tablet=&#8220;40&#8243; margin_bottom_phone=&#8220;35&#8243;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bottom_padding=&#8220;40&#8243; left_padding_desktop=&#8220;35&#8243; right_padding_desktop=&#8220;30&#8243; bottom_padding_phone=&#8220;30&#8243; left_padding_phone=&#8220;20&#8243; right_padding_phone=&#8220;20&#8243; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;padding-7-percent&#8220; column_padding_tablet=&#8220;padding-5-percent&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;right&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; el_class=&#8220;padding-0&#8243; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][vc_custom_heading text=&#8220;\u00d6sterreich&#8220; font_container=&#8220;tag:p|font_size:36px|text_align:left|color:%230a3184|line_height:42px&#8220; use_theme_fonts=&#8220;yes&#8220; el_class=&#8220;bold margin-0 padding-0&#8243;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;26px&#8220; custom_height_tablet=&#8220;25px&#8220; custom_height_phone=&#8220;20px&#8220;][vc_column_text el_class=&#8220;small-text&#8220;]<span style=\"color: #3e3e3e;\">Smart Communications<\/span><br \/>\n<span style=\"color: #3e3e3e;\">Kaerntnerring 5-7,<\/span><br \/>\n<span style=\"color: #3e3e3e;\">1010 Vienna<\/span>[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; el_class=&#8220;padding-0&#8243; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">Telefonnummer<\/span><br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"tel:+4312266600\">+43 1 22 666 00<\/a><\/span>[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20px&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">E-Mail-Adresse<br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"mailto:requests@smartcommunications.com\">requests@smartcommunications.com<\/a><\/span><\/span>[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20px&#8220;][vc_column_text el_class=&#8220;margin-0 padding-0 small-text&#8220;]<span style=\"color: #326eef;\">Support-Anfrage<br \/>\n<span style=\"color: #3e3e3e;\"><a style=\"color: #3e3e3e;\" href=\"mailto:support@smartcommunications.com\">support@smartcommunications.com<\/a><\/span><\/span>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; left_margin=&#8220;20&#8243; left_margin_tablet=&#8220;0&#8243; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; el_class=&#8220;padding-0 contact-us-location-card&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_color=&#8220;#eaeaea&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;76&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220;&#8230;<\/p>\n","protected":false},"author":35,"featured_media":61984,"parent":0,"menu_order":167,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-65666","page","type-page","status-publish","has-post-thumbnail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contact Us - Smart Communications<\/title>\n<meta name=\"description\" content=\"Contact Smart Communications today to get in touch with our team and learn more about our products and services. Fill out our online form or give us a call.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact Us - Smart Communications\" \/>\n<meta property=\"og:description\" content=\"Contact Smart Communications today to get in touch with our team and learn more about our products and services. Fill out our online form or give us a call.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.smartcommunications.com\/de\/kontakt\/\" \/>\n<meta property=\"og:site_name\" content=\"Smart Communications\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-30T16:28:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.smartcommunications.com\/wp-content\/uploads\/ContactUs-FeaturedImage_WP-1200x628-1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.smartcommunications.com\/wp-content\/uploads\/ContactUs-FeaturedImage_WP-1200x628-1-1.png\" \/>\n<meta name=\"twitter:site\" content=\"@CCMInnovators\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"11\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact Us - Smart Communications","description":"Contact Smart Communications today to get in touch with our team and learn more about our products and services. Fill out our online form or give us a call.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"de_DE","og_type":"article","og_title":"Contact Us - Smart Communications","og_description":"Contact Smart Communications today to get in touch with our team and learn more about our products and services. Fill out our online form or give us a call.","og_url":"https:\/\/www.smartcommunications.com\/de\/kontakt\/","og_site_name":"Smart Communications","article_modified_time":"2026-06-30T16:28:37+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.smartcommunications.com\/wp-content\/uploads\/ContactUs-FeaturedImage_WP-1200x628-1-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/www.smartcommunications.com\/wp-content\/uploads\/ContactUs-FeaturedImage_WP-1200x628-1-1.png","twitter_site":"@CCMInnovators","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.smartcommunications.com\/de\/kontakt\/","url":"https:\/\/www.smartcommunications.com\/de\/kontakt\/","name":"Contact Us - Smart Communications","isPartOf":{"@id":"https:\/\/www.smartcommunications.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.smartcommunications.com\/de\/kontakt\/#primaryimage"},"image":{"@id":"https:\/\/www.smartcommunications.com\/de\/kontakt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.smartcommunications.com\/wp-content\/uploads\/ContactUs-FeaturedImage_WP-1200x628-1-1.png","datePublished":"2023-12-18T18:02:34+00:00","dateModified":"2026-06-30T16:28:37+00:00","description":"Contact Smart Communications today to get in touch with our team and learn more about our products and services. Fill out our online form or give us a call.","breadcrumb":{"@id":"https:\/\/www.smartcommunications.com\/de\/kontakt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.smartcommunications.com\/de\/kontakt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.smartcommunications.com\/de\/kontakt\/#primaryimage","url":"https:\/\/www.smartcommunications.com\/wp-content\/uploads\/ContactUs-FeaturedImage_WP-1200x628-1-1.png","contentUrl":"https:\/\/www.smartcommunications.com\/wp-content\/uploads\/ContactUs-FeaturedImage_WP-1200x628-1-1.png","width":1200,"height":628,"caption":"Contact Smart Communications feature image"},{"@type":"BreadcrumbList","@id":"https:\/\/www.smartcommunications.com\/de\/kontakt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.smartcommunications.com\/de\/"},{"@type":"ListItem","position":2,"name":"Contact Us"}]},{"@type":"WebSite","@id":"https:\/\/www.smartcommunications.com\/#website","url":"https:\/\/www.smartcommunications.com\/","name":"Smart Communications","description":"Customer Communication Management Software","publisher":{"@id":"https:\/\/www.smartcommunications.com\/#organization"},"alternateName":"Smart Communications","inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.smartcommunications.com\/#organization","name":"Smart Communications","alternateName":"Smart Communications","url":"https:\/\/www.smartcommunications.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.smartcommunications.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.smartcommunications.com\/wp-content\/uploads\/2017\/03\/Nav_logo_color_hires.png","contentUrl":"https:\/\/www.smartcommunications.com\/wp-content\/uploads\/2017\/03\/Nav_logo_color_hires.png","width":415,"height":140,"caption":"Smart Communications"},"image":{"@id":"https:\/\/www.smartcommunications.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/CCMInnovators","https:\/\/www.linkedin.com\/company\/smart-communications.\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.smartcommunications.com\/de\/wp-json\/wp\/v2\/pages\/65666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.smartcommunications.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.smartcommunications.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.smartcommunications.com\/de\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smartcommunications.com\/de\/wp-json\/wp\/v2\/comments?post=65666"}],"version-history":[{"count":3,"href":"https:\/\/www.smartcommunications.com\/de\/wp-json\/wp\/v2\/pages\/65666\/revisions"}],"predecessor-version":[{"id":77996,"href":"https:\/\/www.smartcommunications.com\/de\/wp-json\/wp\/v2\/pages\/65666\/revisions\/77996"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.smartcommunications.com\/de\/wp-json\/wp\/v2\/media\/61984"}],"wp:attachment":[{"href":"https:\/\/www.smartcommunications.com\/de\/wp-json\/wp\/v2\/media?parent=65666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}